{"id":3236,"date":"2025-05-21T16:35:45","date_gmt":"2025-05-21T14:35:45","guid":{"rendered":"https:\/\/www.cfa-les3bvitre.com\/?page_id=3236"},"modified":"2026-05-12T12:01:46","modified_gmt":"2026-05-12T10:01:46","slug":"offres-bierologue-zythologue","status":"publish","type":"page","link":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/","title":{"rendered":"Offres Bi\u00e9rologue Zythologue"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\" style=\"font-style:normal;font-weight:600\"><strong>Formation Bi\u00e9rologue Zythologue<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4389\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2-1024x1024.png\" alt=\"\" class=\"wp-image-4389\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4519\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-3-1024x1024.png\" alt=\"\" class=\"wp-image-4519\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-3-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-3-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-3-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-3-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-3-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-3.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4521\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-4-1024x1024.png\" alt=\"\" class=\"wp-image-4521\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-4-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-4-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-4-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-4-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-4-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-4.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4594\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/majBZ2026-5-1024x1024.png\" alt=\"\" class=\"wp-image-4594\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/majBZ2026-5-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/majBZ2026-5-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/majBZ2026-5-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/majBZ2026-5-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/majBZ2026-5-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/majBZ2026-5.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4595\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-6-1024x1024.png\" alt=\"\" class=\"wp-image-4595\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-6-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-6-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-6-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-6-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-6-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/04\/BZ2026-6.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4604\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-7-1024x1024.png\" alt=\"\" class=\"wp-image-4604\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-7-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-7-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-7-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-7-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-7-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-7.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4602\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-8-1024x1024.png\" alt=\"\" class=\"wp-image-4602\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-8-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-8-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-8-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-8-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-8-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-8.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4603\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-9-1024x1024.png\" alt=\"\" class=\"wp-image-4603\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-9-1024x1024.png 1024w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-9-300x300.png 300w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-9-150x150.png 150w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-9-768x768.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-9-600x600.png 600w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/05\/BZ2026-9.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Formation Bi\u00e9rologue Zythologue<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","_regular_price":[],"currency_symbol":[],"footnotes":""},"class_list":["post-3236","page","type-page","status-publish","hentry"],"post_slider_layout_featured_media_urls":{"thumbnail":"","post_slider_layout_landscape_large":"","post_slider_layout_portrait_large":"","post_slider_layout_square_large":"","post_slider_layout_landscape":"","post_slider_layout_portrait":"","post_slider_layout_square":"","full":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Offres Bi\u00e9rologue Zythologue - CFA Les 3B Vitr\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offres Bi\u00e9rologue Zythologue - CFA Les 3B Vitr\u00e9\" \/>\n<meta property=\"og:description\" content=\"Formation Bi\u00e9rologue Zythologue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/\" \/>\n<meta property=\"og:site_name\" content=\"CFA Les 3B Vitr\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfales3bvitre\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:01:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/\",\"name\":\"Offres Bi\u00e9rologue Zythologue - CFA Les 3B Vitr\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/BZ2026-2-1024x1024.png\",\"datePublished\":\"2025-05-21T14:35:45+00:00\",\"dateModified\":\"2026-05-12T10:01:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/BZ2026-2.png\",\"contentUrl\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/BZ2026-2.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/offres-bierologue-zythologue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offres Bi\u00e9rologue Zythologue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/\",\"name\":\"CFA Les 3B Vitr\u00e9\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#organization\",\"name\":\"CFA LES 3B VITR\u00c9\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-LOGO-CFA-LES-3B-site-web-07.png\",\"contentUrl\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-LOGO-CFA-LES-3B-site-web-07.png\",\"width\":240,\"height\":149,\"caption\":\"CFA LES 3B VITR\u00c9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cfales3bvitre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cfa-les-3b\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offres Bi\u00e9rologue Zythologue - CFA Les 3B Vitr\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/","og_locale":"fr_FR","og_type":"article","og_title":"Offres Bi\u00e9rologue Zythologue - CFA Les 3B Vitr\u00e9","og_description":"Formation Bi\u00e9rologue Zythologue","og_url":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/","og_site_name":"CFA Les 3B Vitr\u00e9","article_publisher":"https:\/\/www.facebook.com\/cfales3bvitre","article_modified_time":"2026-05-12T10:01:46+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/","url":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/","name":"Offres Bi\u00e9rologue Zythologue - CFA Les 3B Vitr\u00e9","isPartOf":{"@id":"https:\/\/www.cfa-les3bvitre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/#primaryimage"},"image":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2-1024x1024.png","datePublished":"2025-05-21T14:35:45+00:00","dateModified":"2026-05-12T10:01:46+00:00","breadcrumb":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/#primaryimage","url":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2.png","contentUrl":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/BZ2026-2.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/offres-bierologue-zythologue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cfa-les3bvitre.com\/"},{"@type":"ListItem","position":2,"name":"Offres Bi\u00e9rologue Zythologue"}]},{"@type":"WebSite","@id":"https:\/\/www.cfa-les3bvitre.com\/#website","url":"https:\/\/www.cfa-les3bvitre.com\/","name":"CFA Les 3B Vitr\u00e9","description":"","publisher":{"@id":"https:\/\/www.cfa-les3bvitre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfa-les3bvitre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cfa-les3bvitre.com\/#organization","name":"CFA LES 3B VITR\u00c9","url":"https:\/\/www.cfa-les3bvitre.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cfa-les3bvitre.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2022\/03\/cropped-LOGO-CFA-LES-3B-site-web-07.png","contentUrl":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2022\/03\/cropped-LOGO-CFA-LES-3B-site-web-07.png","width":240,"height":149,"caption":"CFA LES 3B VITR\u00c9"},"image":{"@id":"https:\/\/www.cfa-les3bvitre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfales3bvitre","https:\/\/www.linkedin.com\/company\/cfa-les-3b\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/pages\/3236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/comments?post=3236"}],"version-history":[{"count":17,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/pages\/3236\/revisions"}],"predecessor-version":[{"id":4605,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/pages\/3236\/revisions\/4605"}],"wp:attachment":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/media?parent=3236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}