{"id":4208,"date":"2024-07-02T14:28:41","date_gmt":"2024-07-02T12:28:41","guid":{"rendered":"https:\/\/www.cfa-les3bvitre.com\/?p=4208"},"modified":"2026-02-05T15:15:29","modified_gmt":"2026-02-05T14:15:29","slug":"vignes-et-degustation-en-bretagne","status":"publish","type":"post","link":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/","title":{"rendered":"Vignes et D\u00e9gustation en Bretagne"},"content":{"rendered":"\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 20%\"><div class=\"wp-block-media-text__content\">\n<p>\u2705 Journ\u00e9e Oenotourisme pour nos apprenti.es <a href=\"https:\/\/www.cfa-les3bvitre.com\/index.php\/programme-formation-sommelier-caviste\/\" type=\"page\" id=\"1121\">sommeliers cavistes<\/a> !<\/p>\n\n\n\n<p>Le 02 juillet 2024, ils ont co-anim\u00e9 une journ\u00e9e Oenotourisme autour des vins bretons avec les apprenant.es du CFA d&rsquo;Auray.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\ud83e\udd1d Collaboration entre le CFA Les 3B et le CFA de Kerplouz \u00e0 Auray<\/p>\n\n\n\n<p>\ud83d\udccd Lieu : <a href=\"https:\/\/www.kerplouz.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">CFA de Kerplouz LaSAlle<\/a> (Auray)<\/p>\n\n\n\n<p><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-724x1024.png\" alt=\"Journ\u00e9e Oenotourisme\" class=\"wp-image-4210 size-full\" srcset=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-724x1024.png 724w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-212x300.png 212w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-768x1086.png 768w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-1086x1536.png 1086w, https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07.png 1414w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ive-ibtana-visual-editorheading\"><div class=\"ive-advanced-text-wrap ive-div-advance-text_f9263e-11 undefined text-center text-md-center text-lg-start text-xl-start\"><div class=\"ive-text-option-parent\"><i class=\"fas fa-wine-glass-alt ive-paragraph-icon\"><\/i><\/div><h2 class=\"ive-heading-parent undefined ive-advanced-text-inner-wrap ive-adv-advance-text_f9263e-11 ive-lh-xs-30 ive-lh-sm-30 ive-lh-md-30 ive-lh-lg-30 ive-lh-xl-30\" id=\"ive-adv-advance-text_f9263e-11\">Des ateliers de d\u00e9gustation intuitive et d&rsquo;accords Mets &amp; Vins <\/h2><\/div><\/div>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:17px\">Nos apprenti.es sommeliers cavistes ont anim\u00e9 avec brio des ateliers de d\u00e9gustations intuitives puis d&rsquo;accords Mets &amp; Vins.<\/p>\n\n\n\n<p style=\"font-size:17px\">L&rsquo;occasion d&rsquo;\u00e9changer avec l&rsquo;Association pour la Reconnaissance des Vins Bretons et \u00e0 l\u2019Association des Vignerons Bretons.<\/p>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ive-ibtana-visual-editorheading\"><div class=\"ive-advanced-text-wrap ive-div-advance-text_405d37-fc undefined text-center text-md-center text-lg-start text-xl-start\"><div class=\"ive-text-option-parent\"><i class=\"fas fa-tractor ive-paragraph-icon\"><\/i><\/div><h2 class=\"ive-heading-parent undefined ive-advanced-text-inner-wrap ive-adv-advance-text_405d37-fc ive-lh-xs-30 ive-lh-sm-30 ive-lh-md-30 ive-lh-lg-30 ive-lh-xl-30\" id=\"ive-adv-advance-text_405d37-fc\"> Visite de la parcelle p\u00e9dagogique et du chai du Lyc\u00e9e de Kerplouz LaSalle<\/h2><\/div><\/div>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:17px\">Les apprenti.es en Viti-viniculture ont organis\u00e9 une visite de la parcelle p\u00e9dagogique et du chai.<\/p>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ive-ibtana-visual-editorheading\"><div class=\"ive-advanced-text-wrap ive-div-advance-text_a9f2e0-fd undefined text-center text-md-center text-lg-start text-xl-start\"><div class=\"ive-text-option-parent\"><i class=\"fas fa-diagnoses ive-paragraph-icon\"><\/i><\/div><h2 class=\"ive-heading-parent undefined ive-advanced-text-inner-wrap ive-adv-advance-text_a9f2e0-fd ive-lh-xs-30 ive-lh-sm-30 ive-lh-md-30 ive-lh-lg-30 ive-lh-xl-30\" id=\"ive-adv-advance-text_a9f2e0-fd\">Cl\u00f4ture de la journ\u00e9e &#8211;  Conf\u00e9rence du vigneron Robin Euvrard<\/h2><\/div><\/div>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:17px\">En fin de journ\u00e9e, l&rsquo;ensemble des participants a pu assister \u00e0 une conf\u00e9rence du vigneron Robin Euvrard sur le th\u00e8me \u00ab\u00a0Diversification agricole en Bretagne, un d\u00e9fi pour garantir la biodiversit\u00e9\u00a0\u00bb<\/p>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-instagram  wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/cfales3bvitre\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/cfales3bvitre\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li><\/ul>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos apprenti.es sommeliers cavistes ont anim\u00e9 avec brio des ateliers de d\u00e9gustations intuitives puis d&rsquo;accords Mets &amp; Vins. L&rsquo;occasion d&rsquo;\u00e9changer avec l&rsquo;Association pour la Reconnaissance des Vins Bretons et \u00e0 l\u2019Association des Vignerons Bretons. Les apprenti.es en Viti-viniculture ont organis\u00e9 une visite de la parcelle p\u00e9dagogique et du chai. En fin de journ\u00e9e, l&rsquo;ensemble des [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4210,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_regular_price":[],"currency_symbol":[],"footnotes":""},"categories":[28],"tags":[],"class_list":["post-4208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-passes"],"post_slider_layout_featured_media_urls":{"thumbnail":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-150x150.png",150,150,true],"post_slider_layout_landscape_large":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-1200x800.png",1200,800,true],"post_slider_layout_portrait_large":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-1200x1800.png",1200,1800,true],"post_slider_layout_square_large":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-1200x1200.png",1200,1200,true],"post_slider_layout_landscape":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-600x400.png",600,400,true],"post_slider_layout_portrait":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-600x900.png",600,900,true],"post_slider_layout_square":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-600x600.png",600,600,true],"full":["https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07.png",1414,2000,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vignes et D\u00e9gustation en Bretagne - Journ\u00e9e Oenotourisme<\/title>\n<meta name=\"description\" content=\"Journ\u00e9e Oenotourisme autour des vins bretons organis\u00e9e par les apprenti.es du CFA Les 3B, en partenariat avec le lyc\u00e9e de Kerplouz LaSAlle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vignes et D\u00e9gustation en Bretagne - Journ\u00e9e Oenotourisme\" \/>\n<meta property=\"og:description\" content=\"Journ\u00e9e Oenotourisme autour des vins bretons organis\u00e9e par les apprenti.es du CFA Les 3B, en partenariat avec le lyc\u00e9e de Kerplouz LaSAlle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/\" \/>\n<meta property=\"og:site_name\" content=\"CFA Les 3B Vitr\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfales3bvitre\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T12:28:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T14:15:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-724x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Camille Bertho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Bertho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/\"},\"author\":{\"name\":\"Camille Bertho\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#\\\/schema\\\/person\\\/8bc7856816c526ae1294d9b5288e4a9a\"},\"headline\":\"Vignes et D\u00e9gustation en Bretagne\",\"datePublished\":\"2024-07-02T12:28:41+00:00\",\"dateModified\":\"2026-02-05T14:15:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/AFFICHE-AURAY-SCAG07.png\",\"articleSection\":[\"Pass\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/\",\"name\":\"Vignes et D\u00e9gustation en Bretagne - Journ\u00e9e Oenotourisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/AFFICHE-AURAY-SCAG07.png\",\"datePublished\":\"2024-07-02T12:28:41+00:00\",\"dateModified\":\"2026-02-05T14:15:29+00:00\",\"description\":\"Journ\u00e9e Oenotourisme autour des vins bretons organis\u00e9e par les apprenti.es du CFA Les 3B, en partenariat avec le lyc\u00e9e de Kerplouz LaSAlle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/AFFICHE-AURAY-SCAG07.png\",\"contentUrl\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/AFFICHE-AURAY-SCAG07.png\",\"width\":1414,\"height\":2000,\"caption\":\"Affiche journ\u00e9e Oenotourisme Auray\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/2024\\\/07\\\/02\\\/vignes-et-degustation-en-bretagne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vignes et D\u00e9gustation en Bretagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/\",\"name\":\"CFA Les 3B Vitr\u00e9\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#organization\",\"name\":\"CFA LES 3B VITR\u00c9\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-LOGO-CFA-LES-3B-site-web-07.png\",\"contentUrl\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-LOGO-CFA-LES-3B-site-web-07.png\",\"width\":240,\"height\":149,\"caption\":\"CFA LES 3B VITR\u00c9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cfales3bvitre\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cfa-les-3b\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/#\\\/schema\\\/person\\\/8bc7856816c526ae1294d9b5288e4a9a\",\"name\":\"Camille Bertho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df4834bbd79a0156d81f23d950e727edb333e445d6e4b252c6c270fc0d545ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df4834bbd79a0156d81f23d950e727edb333e445d6e4b252c6c270fc0d545ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df4834bbd79a0156d81f23d950e727edb333e445d6e4b252c6c270fc0d545ca?s=96&d=mm&r=g\",\"caption\":\"Camille Bertho\"},\"url\":\"https:\\\/\\\/www.cfa-les3bvitre.com\\\/index.php\\\/author\\\/camille\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vignes et D\u00e9gustation en Bretagne - Journ\u00e9e Oenotourisme","description":"Journ\u00e9e Oenotourisme autour des vins bretons organis\u00e9e par les apprenti.es du CFA Les 3B, en partenariat avec le lyc\u00e9e de Kerplouz LaSAlle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/","og_locale":"fr_FR","og_type":"article","og_title":"Vignes et D\u00e9gustation en Bretagne - Journ\u00e9e Oenotourisme","og_description":"Journ\u00e9e Oenotourisme autour des vins bretons organis\u00e9e par les apprenti.es du CFA Les 3B, en partenariat avec le lyc\u00e9e de Kerplouz LaSAlle.","og_url":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/","og_site_name":"CFA Les 3B Vitr\u00e9","article_publisher":"https:\/\/www.facebook.com\/cfales3bvitre","article_published_time":"2024-07-02T12:28:41+00:00","article_modified_time":"2026-02-05T14:15:29+00:00","og_image":[{"width":724,"height":1024,"url":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07-724x1024.png","type":"image\/png"}],"author":"Camille Bertho","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Camille Bertho","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/#article","isPartOf":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/"},"author":{"name":"Camille Bertho","@id":"https:\/\/www.cfa-les3bvitre.com\/#\/schema\/person\/8bc7856816c526ae1294d9b5288e4a9a"},"headline":"Vignes et D\u00e9gustation en Bretagne","datePublished":"2024-07-02T12:28:41+00:00","dateModified":"2026-02-05T14:15:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/"},"wordCount":179,"publisher":{"@id":"https:\/\/www.cfa-les3bvitre.com\/#organization"},"image":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07.png","articleSection":["Pass\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/","url":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/","name":"Vignes et D\u00e9gustation en Bretagne - Journ\u00e9e Oenotourisme","isPartOf":{"@id":"https:\/\/www.cfa-les3bvitre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/#primaryimage"},"image":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07.png","datePublished":"2024-07-02T12:28:41+00:00","dateModified":"2026-02-05T14:15:29+00:00","description":"Journ\u00e9e Oenotourisme autour des vins bretons organis\u00e9e par les apprenti.es du CFA Les 3B, en partenariat avec le lyc\u00e9e de Kerplouz LaSAlle.","breadcrumb":{"@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/#primaryimage","url":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07.png","contentUrl":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2026\/02\/AFFICHE-AURAY-SCAG07.png","width":1414,"height":2000,"caption":"Affiche journ\u00e9e Oenotourisme Auray"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfa-les3bvitre.com\/index.php\/2024\/07\/02\/vignes-et-degustation-en-bretagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cfa-les3bvitre.com\/"},{"@type":"ListItem","position":2,"name":"Vignes et D\u00e9gustation en Bretagne"}]},{"@type":"WebSite","@id":"https:\/\/www.cfa-les3bvitre.com\/#website","url":"https:\/\/www.cfa-les3bvitre.com\/","name":"CFA Les 3B Vitr\u00e9","description":"","publisher":{"@id":"https:\/\/www.cfa-les3bvitre.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfa-les3bvitre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cfa-les3bvitre.com\/#organization","name":"CFA LES 3B VITR\u00c9","url":"https:\/\/www.cfa-les3bvitre.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cfa-les3bvitre.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2022\/03\/cropped-LOGO-CFA-LES-3B-site-web-07.png","contentUrl":"https:\/\/www.cfa-les3bvitre.com\/wp-content\/uploads\/2022\/03\/cropped-LOGO-CFA-LES-3B-site-web-07.png","width":240,"height":149,"caption":"CFA LES 3B VITR\u00c9"},"image":{"@id":"https:\/\/www.cfa-les3bvitre.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfales3bvitre","https:\/\/www.linkedin.com\/company\/cfa-les-3b\/"]},{"@type":"Person","@id":"https:\/\/www.cfa-les3bvitre.com\/#\/schema\/person\/8bc7856816c526ae1294d9b5288e4a9a","name":"Camille Bertho","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3df4834bbd79a0156d81f23d950e727edb333e445d6e4b252c6c270fc0d545ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3df4834bbd79a0156d81f23d950e727edb333e445d6e4b252c6c270fc0d545ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3df4834bbd79a0156d81f23d950e727edb333e445d6e4b252c6c270fc0d545ca?s=96&d=mm&r=g","caption":"Camille Bertho"},"url":"https:\/\/www.cfa-les3bvitre.com\/index.php\/author\/camille\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/posts\/4208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/comments?post=4208"}],"version-history":[{"count":7,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/posts\/4208\/revisions"}],"predecessor-version":[{"id":4227,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/posts\/4208\/revisions\/4227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/media\/4210"}],"wp:attachment":[{"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/media?parent=4208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/categories?post=4208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfa-les3bvitre.com\/index.php\/wp-json\/wp\/v2\/tags?post=4208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}